 {"id":54,"count":20,"description":"Art\u00edculos relacionados con la aplicaci\u00f3n DHIS2 Android Capture","link":"https:\/\/education.dhis2.org\/es\/category\/android-es\/","name":"Android","slug":"android-es","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Android - DHIS2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/education.dhis2.org\/es\/category\/android-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Android - DHIS2\" \/>\n<meta property=\"og:description\" content=\"Art\u00edculos relacionados con la aplicaci\u00f3n DHIS2 Android Capture\" \/>\n<meta property=\"og:url\" content=\"https:\/\/education.dhis2.org\/es\/category\/android-es\/\" \/>\n<meta property=\"og:site_name\" content=\"DHIS2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/category\\\/android-es\\\/\",\"url\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/category\\\/android-es\\\/\",\"name\":\"Android - DHIS2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/category\\\/android-es\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/category\\\/android-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Android\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/\",\"name\":\"DHIS2\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/#organization\",\"name\":\"DHIS2\",\"url\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/education.dhis2.org\\\/wp-content\\\/uploads\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/education.dhis2.org\\\/wp-content\\\/uploads\\\/logo.svg\",\"caption\":\"DHIS2\"},\"image\":{\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Android - DHIS2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/education.dhis2.org\/es\/category\/android-es\/","og_locale":"es_ES","og_type":"article","og_title":"Android - DHIS2","og_description":"Art\u00edculos relacionados con la aplicaci\u00f3n DHIS2 Android Capture","og_url":"https:\/\/education.dhis2.org\/es\/category\/android-es\/","og_site_name":"DHIS2","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/education.dhis2.org\/es\/category\/android-es\/","url":"https:\/\/education.dhis2.org\/es\/category\/android-es\/","name":"Android - DHIS2","isPartOf":{"@id":"https:\/\/education.dhis2.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/education.dhis2.org\/es\/category\/android-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/education.dhis2.org\/es\/category\/android-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/education.dhis2.org\/es\/"},{"@type":"ListItem","position":2,"name":"Android"}]},{"@type":"WebSite","@id":"https:\/\/education.dhis2.org\/es\/#website","url":"https:\/\/education.dhis2.org\/es\/","name":"DHIS2","description":"","publisher":{"@id":"https:\/\/education.dhis2.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/education.dhis2.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/education.dhis2.org\/es\/#organization","name":"DHIS2","url":"https:\/\/education.dhis2.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/education.dhis2.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/education.dhis2.org\/wp-content\/uploads\/logo.svg","contentUrl":"https:\/\/education.dhis2.org\/wp-content\/uploads\/logo.svg","caption":"DHIS2"},"image":{"@id":"https:\/\/education.dhis2.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/education.dhis2.org\/es\/wp-json\/wp\/v2\/categories\/54","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/education.dhis2.org\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/education.dhis2.org\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/education.dhis2.org\/es\/wp-json\/wp\/v2\/posts?categories=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}