 {"id":20941,"date":"2024-12-16T22:08:10","date_gmt":"2024-12-16T21:08:10","guid":{"rendered":"https:\/\/education.dhis2.org\/noticias-y-actualizaciones\/"},"modified":"2024-12-16T22:08:10","modified_gmt":"2024-12-16T21:08:10","slug":"news","status":"publish","type":"page","link":"https:\/\/education.dhis2.org\/es\/news\/","title":{"rendered":"Noticias y actualizaciones"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p class=\"lead\">Mantente al d\u00eda de las \u00faltimas noticias sobre DHIS2 para la educaci\u00f3n, incluyendo proyectos educativos, resultados de investigaciones, pr\u00f3ximos eventos y mucho m\u00e1s.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-news-archive.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-20941","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Noticias y actualizaciones - DHIS2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/education.dhis2.org\/es\/news\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noticias y actualizaciones - DHIS2\" \/>\n<meta property=\"og:description\" content=\"Mantente al d\u00eda de las \u00faltimas noticias sobre DHIS2 para la educaci\u00f3n, incluyendo proyectos educativos, resultados de investigaciones, pr\u00f3ximos eventos y mucho m\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/education.dhis2.org\/es\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"DHIS2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/news\\\/\",\"url\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/news\\\/\",\"name\":\"Noticias y actualizaciones - DHIS2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/#website\"},\"datePublished\":\"2024-12-16T21:08:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/news\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/education.dhis2.org\\\/es\\\/news\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias y actualizaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/\",\"name\":\"DHIS2\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/#organization\",\"name\":\"DHIS2\",\"url\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/education.dhis2.org\\\/wp-content\\\/uploads\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/education.dhis2.org\\\/wp-content\\\/uploads\\\/logo.svg\",\"caption\":\"DHIS2\"},\"image\":{\"@id\":\"https:\\\/\\\/education.dhis2.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Noticias y actualizaciones - DHIS2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/education.dhis2.org\/es\/news\/","og_locale":"es_ES","og_type":"article","og_title":"Noticias y actualizaciones - DHIS2","og_description":"Mantente al d\u00eda de las \u00faltimas noticias sobre DHIS2 para la educaci\u00f3n, incluyendo proyectos educativos, resultados de investigaciones, pr\u00f3ximos eventos y mucho m\u00e1s.","og_url":"https:\/\/education.dhis2.org\/es\/news\/","og_site_name":"DHIS2","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/education.dhis2.org\/es\/news\/","url":"https:\/\/education.dhis2.org\/es\/news\/","name":"Noticias y actualizaciones - DHIS2","isPartOf":{"@id":"https:\/\/education.dhis2.org\/es\/#website"},"datePublished":"2024-12-16T21:08:10+00:00","breadcrumb":{"@id":"https:\/\/education.dhis2.org\/es\/news\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/education.dhis2.org\/es\/news\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/education.dhis2.org\/es\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/education.dhis2.org\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias y actualizaciones"}]},{"@type":"WebSite","@id":"https:\/\/education.dhis2.org\/es\/#website","url":"https:\/\/education.dhis2.org\/es\/","name":"DHIS2","description":"","publisher":{"@id":"https:\/\/education.dhis2.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/education.dhis2.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/education.dhis2.org\/es\/#organization","name":"DHIS2","url":"https:\/\/education.dhis2.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/education.dhis2.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/education.dhis2.org\/wp-content\/uploads\/logo.svg","contentUrl":"https:\/\/education.dhis2.org\/wp-content\/uploads\/logo.svg","caption":"DHIS2"},"image":{"@id":"https:\/\/education.dhis2.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/education.dhis2.org\/es\/wp-json\/wp\/v2\/pages\/20941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/education.dhis2.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/education.dhis2.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/education.dhis2.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/education.dhis2.org\/es\/wp-json\/wp\/v2\/comments?post=20941"}],"version-history":[{"count":0,"href":"https:\/\/education.dhis2.org\/es\/wp-json\/wp\/v2\/pages\/20941\/revisions"}],"wp:attachment":[{"href":"https:\/\/education.dhis2.org\/es\/wp-json\/wp\/v2\/media?parent=20941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}